{"id":1128,"count":1,"description":"","link":"https:\/\/www.windsport.co.uk\/wordpress\/product-category\/parts-spares\/dart-20\/accessories-dart-20\/books-accessories-dart-20\/","name":"Books (D20)","slug":"books-accessories-dart-20","taxonomy":"product_cat","parent":1095,"meta":[],"menu_order":187,"_links":{"self":[{"href":"https:\/\/www.windsport.co.uk\/wordpress\/wp-json\/wp\/v2\/product_cat\/1128","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.windsport.co.uk\/wordpress\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/www.windsport.co.uk\/wordpress\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/www.windsport.co.uk\/wordpress\/wp-json\/wp\/v2\/product_cat\/1095"}],"wp:post_type":[{"href":"https:\/\/www.windsport.co.uk\/wordpress\/wp-json\/wp\/v2\/product?product_cat=1128"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}